{"id":9894,"date":"2021-07-23T19:54:41","date_gmt":"2021-07-23T19:54:41","guid":{"rendered":"https:\/\/forestmap.eu\/?p=9894"},"modified":"2022-07-22T11:36:39","modified_gmt":"2022-07-22T11:36:39","slug":"inventario-lidar-na-zona-piloto-do-forestmap-em-portugal","status":"publish","type":"post","link":"https:\/\/forestmap.eu\/pt-pt\/inventario-lidar-na-zona-piloto-do-forestmap-em-portugal\/","title":{"rendered":"Invent\u00e1rio LiDAR na zona piloto do ForestMap em Portugal"},"content":{"rendered":"\n<p>O invent\u00e1rio da \u00e1rea piloto no norte de Portugal, cobrindo cerca de 12.900 ha nos munic\u00edpios de Mondim de Basto, Amarante e Celorico de Basto, est\u00e1 a ser finalizado. Temos resultados preliminares que estamos a verificar, corrigir e refinar.<\/p>\n\n<p>Ap\u00f3s um voo de recolha de dados em Junho de 2020, foram realizadas duas campanhas de recolha de dados de campo, com parcelas em estratos de pinho mar\u00edtimo e eucalipto. No ano passado, as visitas de campo foram complicadas e tiveram de ser adiadas v\u00e1rias vezes devido a restri\u00e7\u00f5es relacionadas com a pandemia.<\/p>\n\n<p>Particip\u00e1mos recentemente em dois workshops organizados pelos nossos parceiros neste projecto-piloto. Um deles foi uma confer\u00eancia presencial no dia 19 de Junho, para a qual fomos convidados por Baladi, como parte de uma reuni\u00e3o de grupos de Baladi, com a participa\u00e7\u00e3o da Secretaria de Estado para a Conserva\u00e7\u00e3o da Natureza, Florestas e Ordenamento do Territ\u00f3rio de Portugal.<\/p>\n\n<p>Particip\u00e1mos na visita de campo de manh\u00e3 e, \u00e0 tarde, no \u00e2mbito de um programa mais vasto de confer\u00eancias sobre &#8220;Bald\u00edos&#8221;, tivemos um espa\u00e7o para apresentar o invent\u00e1rio LiDAR realizado na zona piloto, onde uma elevada propor\u00e7\u00e3o de propriedades s\u00e3o &#8220;Bald\u00edos&#8221;.<\/p>\n<div id=\"pictures\">\r\n        <div class=\"wp-block-image\">\r\n            <figure class=\"aligncenter size-large\">\r\n                <img decoding=\"async\" src=\"https:\/\/forestmap.eu\/wp-content\/uploads\/Post2Foto-2_jornada-Baladi-1200.jpg\" alt=\"\" class=\"wp-image-9856\"\/>\r\n            <figcaption>As explica\u00e7\u00f5es de Baladi na vis\u00e3o de campo da reuni\u00e3o de Baldios.<\/figcaption><\/figure>\r\n        <\/div>\r\n        <div class=\"wp-block-image\">\r\n            <figure class=\"aligncenter size-large\">\r\n                <img decoding=\"async\" src=\"https:\/\/forestmap.eu\/wp-content\/uploads\/Post2Foto-1_visita-de-campo-Baladi-scaled-1-1200.jpg\" alt=\"\" class=\"wp-image-9856\"\/>\r\n            <figcaption>David Garc\u00eda Castillo, da Agresta, apresentando o invent\u00e1rio LIDAR.<\/figcaption><\/figure>\r\n        <\/div>\r\n    <\/div>\r\n\n<p>Os &#8220;Bald\u00edos&#8221; s\u00e3o um tipo muito particular de propriedade; s\u00e3o propriedades comunais que pertencem aos vizinhos. Poder\u00edamos dizer que s\u00e3o o equivalente \u00e0s terras comuns dos vizinhos, que s\u00e3o t\u00e3o comuns na Galiza.<\/p>\n\n<p>A 30 de Junho realizou-se uma confer\u00eancia organizada pelo Centro Pinus no \u00e2mbito do projecto-piloto para apresentar as primeiras conclus\u00f5es sobre os resultados que estamos a obter do invent\u00e1rio e para manter um di\u00e1logo com os participantes. O evento foi planeado para ser realizado pessoalmente mas finalmente teve de ser realizado on-line devido a complica\u00e7\u00f5es causadas pela Covid em Portugal. Uma das utiliza\u00e7\u00f5es mais interessantes deste trabalho \u00e9 o combate aos inc\u00eandios florestais, uma vez que neste projecto-piloto est\u00e1 a ser elaborada uma cartografia b\u00e1sica de modelos de combust\u00edvel, com um car\u00e1cter demonstrativo.<\/p>\n\n<p>A tecnologia LiDAR permite analisar a estrutura da vegeta\u00e7\u00e3o em toda a \u00e1rea de estudo, o que \u00e9 de grande valor para a tomada de decis\u00f5es sobre a prioriza\u00e7\u00e3o e localiza\u00e7\u00e3o dos trabalhos de preven\u00e7\u00e3o, tanto para interven\u00e7\u00f5es florestais como para a cria\u00e7\u00e3o e manuten\u00e7\u00e3o de infra-estruturas.<\/p>\n\n<p>Os resultados deste invent\u00e1rio ser\u00e3o disponibilizados na plataforma ForestMap at\u00e9 ao final de 2021 atrav\u00e9s de um modelo de acesso espec\u00edfico para cada tipo de utilizador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O invent\u00e1rio da \u00e1rea piloto no norte de Portugal, cobrindo cerca de 12.900 ha nos munic\u00edpios de Mondim de Basto, Amarante e Celorico de Basto, est\u00e1 a ser finalizado. Temos resultados preliminares que estamos a verificar, corrigir e refinar. Ap\u00f3s um voo de recolha de dados em Junho de 2020, foram realizadas duas campanhas de &#8230; <a title=\"Invent\u00e1rio LiDAR na zona piloto do ForestMap em Portugal\" class=\"read-more\" href=\"https:\/\/forestmap.eu\/pt-pt\/inventario-lidar-na-zona-piloto-do-forestmap-em-portugal\/\" aria-label=\"Mais em Invent\u00e1rio LiDAR na zona piloto do ForestMap em Portugal\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":9372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,10],"tags":[],"class_list":["post-9894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","category-uncategorized","no-featured-image-padding","resize-featured-image"],"_links":{"self":[{"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/posts\/9894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/comments?post=9894"}],"version-history":[{"count":1,"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/posts\/9894\/revisions"}],"predecessor-version":[{"id":9895,"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/posts\/9894\/revisions\/9895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/media\/9372"}],"wp:attachment":[{"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=9894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/categories?post=9894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forestmap.eu\/pt-pt\/wp-json\/wp\/v2\/tags?post=9894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}